{"id":3764,"date":"2025-07-29T10:04:14","date_gmt":"2025-07-29T03:04:14","guid":{"rendered":"https:\/\/onepack.casethemes.net\/?p=3764"},"modified":"2025-07-29T10:04:14","modified_gmt":"2025-07-29T03:04:14","slug":"designing-prestige-our-properties-reflect-legacy-luxury-and-longevity","status":"publish","type":"post","link":"https:\/\/sivokogroup.com\/real-estate\/designing-prestige-our-properties-reflect-legacy-luxury-and-longevity\/","title":{"rendered":"Designing prestige: Our properties reflect legacy, luxury, and longevity"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3764\" class=\"elementor elementor-3764\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e49494 e-flex e-con-boxed pxl-row-scroll-none pxl-column-none pxl-full-content-with-space-none e-con e-parent \" data-id=\"8e49494\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-62fd8b9 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"62fd8b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>In today\u2019s interconnected world, health challenges are global\u2014and so are the solutions. The Global Health Connect Podcast explores the intersection of global healthcare and innovative partnerships. Join us as we uncover the stories, insights, and strategies of leaders shaping the future of health around the globe. Whether you&#8217;re a healthcare professional, policymaker, researcher, or simply someone passionate about improving health outcomes worldwide, this podcast is for you. Every episode dives deep into topics such as:<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-768b77e elementor-widget elementor-widget-pxl_text_editor\" data-id=\"768b77e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>Hosted by leading experts in global health, each episode of the Global Health Connect Podcast dives into critical discussions with thought leaders, innovators, and changemakers from around the world.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-488c9e5 elementor-widget elementor-widget-pxl_heading\" data-id=\"488c9e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-488c9e5-3196\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h5 class=\"pxl-item--title style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\tEach episode is designed to leave listeners\t\t\t<\/h5>\n\n\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb0b85b elementor-widget elementor-widget-pxl_text_editor\" data-id=\"cb0b85b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>Our hosts bring decades of experience in global health, working on the frontlines of healthcare delivery, policy-making, and innovation. They\u2019re passionate about creating impactful conversations that spark new ideas and inspire action. From improving infrastructure in low-resource settings to building stronger healthcare workforces, we delve into the systemic issues and creative solutions that can improve global health outcomes.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aefb6d8 e-con-full e-flex pxl-row-scroll-none pxl-column-none pxl-full-content-with-space-none e-con e-child \" data-id=\"aefb6d8\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-ebcce55 elementor-widget elementor-widget-pxl_image\" data-id=\"ebcce55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-ebcce55-9011\" class=\"pxl-image-single     \" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner \" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image \" data-parallax-value=\"\">\r\n                                <img fetchpriority=\"high\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/sivokogroup.com\/real-estate\/wp-content\/uploads\/2025\/06\/user-review-h1-300x450.webp\" width=\"300\" height=\"450\" alt=\"user-review-h1\" title=\"user-review-h1\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-726263b e-con-full e-flex pxl-row-scroll-none pxl-column-none pxl-full-content-with-space-none e-con e-child \" data-id=\"726263b\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-d579860 elementor-widget elementor-widget-pxl_heading\" data-id=\"d579860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-d579860-5204\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h5 class=\"pxl-item--title style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\tDiverse range of guests:\t\t\t<\/h5>\n\n\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c395afa elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c395afa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>            <span class=\"pxl-text--highlight\">\n                Healthcare Providers:             <\/span>\n        From doctors and nurses in rural clinics to administrators of large international hospitals, we bring on-the-ground perspectives about the healthcare.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2cc6e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e2cc6e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb1ebf elementor-widget elementor-widget-pxl_text_editor\" data-id=\"cfb1ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>            <span class=\"pxl-text--highlight\">\n                Global Health Experts:             <\/span>\n        Academics, researchers, and professionals with years of experience in public health share the data, findings, and trends shaping.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02d5964 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"02d5964\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd17d6 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"3dd17d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>            <span class=\"pxl-text--highlight\">\n                Innovators and Entrepreneurs:             <\/span>\n        Discover how tech startups, medical companies, and digital health pioneers are changing the way healthcare is delivered across the globe.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9e21ab0 elementor-widget elementor-widget-pxl_heading\" data-id=\"9e21ab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-9e21ab0-7268\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h5 class=\"pxl-item--title style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\tHow it works?\t\t\t<\/h5>\n\n\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b68c40b elementor-widget elementor-widget-pxl_text_editor\" data-id=\"b68c40b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>Our hosts bring decades of experience in global health, working on the frontlines of healthcare delivery, policy-making, and innovation. They\u2019re passionate about creating impactful conversations that spark new ideas and inspire action. From improving infrastructure in low-resource settings to building stronger healthcare workforces, we delve into the systemic issues and creative solutions that can improve global health outcomes.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-911fc7f e-con-full e-flex pxl-row-scroll-none pxl-column-none pxl-full-content-with-space-none e-con e-child \" data-id=\"911fc7f\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-7ebc170 elementor-widget elementor-widget-pxl_image\" data-id=\"7ebc170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-7ebc170-6181\" class=\"pxl-image-single     \" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner \" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image \" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/sivokogroup.com\/real-estate\/wp-content\/uploads\/2025\/07\/img-cpn-h4-425x300.webp\" width=\"425\" height=\"300\" alt=\"img-cpn-h4\" title=\"img-cpn-h4\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f03a80d elementor-widget elementor-widget-pxl_image\" data-id=\"f03a80d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-f03a80d-7279\" class=\"pxl-image-single     \" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner \" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image \" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/sivokogroup.com\/real-estate\/wp-content\/uploads\/2025\/07\/img-awa-425x300.webp\" width=\"425\" height=\"300\" alt=\"img-awa\" title=\"img-awa\" \/>                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e8fbc82 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"e8fbc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor default\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>In today\u2019s interconnected world, health challenges are global\u2014and so are the solutions. The Global Health Connect Podcast explores the intersection of global healthcare and innovative partnerships. Join us as we uncover the stories, insights, and strategies of leaders shaping the future of health around the globe. Whether you&#8217;re a healthcare professional, policymaker, researcher, or simply someone passionate about improving health outcomes worldwide, this podcast is for you. Every episode dives deep into topics such as:<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>In today\u2019s interconnected world, health challenges are global\u2014and so are the solutions. The Global Health Connect Podcast explores the intersection of global healthcare and innovative partnerships. Join us as we uncover the stories, insights, and strategies of leaders shaping the future of health around the globe. Whether you\u2019re a healthcare professional, policymaker, researcher, or simply [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5,6,7],"class_list":["post-3764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luxury","tag-business","tag-design","tag-wp"],"_links":{"self":[{"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/posts\/3764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/comments?post=3764"}],"version-history":[{"count":0,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/posts\/3764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/media\/3263"}],"wp:attachment":[{"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/media?parent=3764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/categories?post=3764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sivokogroup.com\/real-estate\/wp-json\/wp\/v2\/tags?post=3764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}